{"id":5842,"date":"2022-09-17T08:23:51","date_gmt":"2022-09-17T08:23:51","guid":{"rendered":"https:\/\/dr-fassbender.de\/?p=5842"},"modified":"2025-03-16T08:05:12","modified_gmt":"2025-03-16T08:05:12","slug":"coaching-ist-nicht-nur-etwas-fuer-den-geschaeftsbereich","status":"publish","type":"post","link":"https:\/\/dr-fassbender.de\/en\/coaching-ist-nicht-nur-etwas-fuer-den-geschaeftsbereich\/","title":{"rendered":"Businesscoaching ist mehr als Beratung &#8211; Es sollte sich auch um die Menschen drehen, die das Business bewegen"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5842\" class=\"elementor elementor-5842\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-266c3af elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"266c3af\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c133694\" data-id=\"c133694\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a57737 elementor-widget elementor-widget-heading\" data-id=\"5a57737\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Businesscoaching<br><p style=\"margin: 0cm;font-size: medium;font-family: Calibri, sans-serif;font-weight: normal;text-transform: none;white-space: normal\"><\/p><p style=\"margin: 0cm;font-size: medium;font-family: Calibri, sans-serif;font-weight: normal;text-transform: none;white-space: normal\"><\/p>- Oftmals etwas ganz <br>Anderes, als man Gemeinhin erwartet<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cea90e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2cea90e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f85986\" data-id=\"1f85986\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-711ffc8 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"711ffc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1599\" height=\"170\" src=\"https:\/\/dr-fassbender.de\/wp-content\/uploads\/2021\/12\/banner-shape.png\" class=\"attachment-full size-full wp-image-8\" alt=\"\" srcset=\"https:\/\/dr-fassbender.de\/wp-content\/uploads\/2021\/12\/banner-shape.png 1599w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2021\/12\/banner-shape-300x32.png 300w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2021\/12\/banner-shape-1024x109.png 1024w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2021\/12\/banner-shape-768x82.png 768w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2021\/12\/banner-shape-1536x163.png 1536w\" sizes=\"(max-width: 1599px) 100vw, 1599px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94a4413 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94a4413\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2912f9e\" data-id=\"2912f9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f70dbb elementor-widget elementor-widget-heading\" data-id=\"6f70dbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Businesscoaching ist nicht notwendigerweise auf das Business beschr\u00e4nkt.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb50e29 elementor-widget elementor-widget-text-editor\" data-id=\"bb50e29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Begriff Businesscoaching ist h\u00f6chst irref\u00fchrend. Ja, es sind h\u00e4ufig Unternehmen oder Personen aus Unternehmen, die auf uns zukommen und unsere Expertise im Bereich Coaching suchen. Dennoch ist es erstaunlich, dass auch heute noch viele Interessenten meinen, es geht vor allem um ein Business Consulting. Dies ist, wenn \u00fcberhaupt, nur in einem zweiten Schritt der Fall. Zun\u00e4chst steht die Person im Mittelpunkt, oder das Team, sollte ein solches mit einem Thema an uns herantreten. Vielfach sind es jedoch Einzelpersonen, die \u00fcber den Umweg eines konkreten gesch\u00e4ftlichen Themas eigentlich sehr menschliche Themen auf dem Herzen haben, die einer L\u00f6sungsfindung im beruflichen Kontext im Wege stehen. Daher kommt es h\u00e4ufig vor, dass schon nach kurzer Zeit andere Dinge besprochen werden d\u00fcrfen, als das urspr\u00fcnglich angedachte Hauptthema. Dies ist \u00fcbrigens etwas Gutes. In vielen F\u00e4llen l\u00f6sen sich nach einer Auseinandersetzung mit pers\u00f6nlichen Befindlichkeiten, berufliche Themen wie von selbst. Aber auch wenn dies nur einen ersten Schritt darstellt, erm\u00f6glicht dieser h\u00e4ufig erst den klaren Blick auf die Themen, die nach Ansicht des Coachee&#8217;s eigentlich im Mittelpunkt des Coachings h\u00e4tten stehen sollen. Erstaunlich, wie einfach und unkompliziert dann manchmal die L\u00f6sungen ganz eigenst\u00e4ndig von zun\u00e4chst hilflos wirkenden Personen selbst hergeleitet werden k\u00f6nnen. Es ist immer wieder eine Freude, hieran teilhaben zu d\u00fcrfen.\u00a0<\/p><p>Melden Sie sich gerne bei uns f\u00fcr n\u00e4here Informationen, und wie geschrieben, z\u00f6gern Sie nicht, sich auch bei Themen zu melden, die auf den ersten Blick nicht in den Themenbereich Businesscoaching zu fallen scheinen. Wir freuen uns in jedem Fall \u00fcber Ihre Kontaktaufnahme.<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05edf1a elementor-widget elementor-widget-shortcode\" data-id=\"05edf1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f715307 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f715307\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb056bc\" data-id=\"eb056bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc0a0d4 elementor-widget elementor-widget-heading\" data-id=\"bc0a0d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c4hnliche Themen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4d9e72 blog-section premium-blog-align-left elementor-widget elementor-widget-premium-addon-blog\" data-id=\"c4d9e72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;premium_blog_columns_number&quot;:&quot;33.33%&quot;,&quot;premium_blog_columns_number_tablet&quot;:&quot;33.33%&quot;,&quot;premium_blog_grid&quot;:&quot;yes&quot;,&quot;premium_blog_layout&quot;:&quot;even&quot;,&quot;premium_blog_columns_number_mobile&quot;:&quot;100%&quot;}\" data-widget_type=\"premium-addon-blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\n\n\t\t\t\t<div class=\"premium-blog-wrap  premium-blog-even\" data-page=\"5842\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"2\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumb-effect-wrapper\">\n\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-container premium-blog-none-effect\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"372\" height=\"200\" src=\"https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Justitia-Beitragsbild.png\" class=\"attachment-full size-full wp-image-5832\" alt=\"\" srcset=\"https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Justitia-Beitragsbild.png 372w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Justitia-Beitragsbild-300x161.png 300w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Justitia-Beitragsbild-18x10.png 18w\" sizes=\"(max-width: 372px) 100vw, 372px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-overlay\">\n\t\t\t\t\t\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/dr-fassbender.de\/en\/betreibungen-in-der-schweiz-notariellen-urkunden\/\" target=\"_blank\" aria-label=\"Debt collection in Switzerland from German notarial land charge deeds &quot;Urkunde&quot; (deed)\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/dr-fassbender.de\/en\/betreibungen-in-der-schweiz-notariellen-urkunden\/\" target=\"_blank\">\n\t\t\t\tDebt collection in Switzerland from German notarial land charge deeds \"Urkunde\" (deed)\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-categories premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-align-left fa-fw\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<a href=\"https:\/\/dr-fassbender.de\/en\/category\/aktuelles\/\" rel=\"category tag\">Latest News<\/a>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Usually, German real estate purchase contracts are financed by bank loans, whereby these loans are secured by the creation of a land charge, as well as the personal assumption of liability for the amount of the land charge together with an immediate submission to foreclosure on the entire property....<\/p>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"2\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumb-effect-wrapper\">\n\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-container premium-blog-none-effect\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"372\" height=\"200\" src=\"https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Beitragsbild-Puzzle-weiss.png\" class=\"attachment-full size-full wp-image-5828\" alt=\"\" srcset=\"https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Beitragsbild-Puzzle-weiss.png 372w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Beitragsbild-Puzzle-weiss-300x161.png 300w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Beitragsbild-Puzzle-weiss-18x10.png 18w\" sizes=\"(max-width: 372px) 100vw, 372px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-overlay\">\n\t\t\t\t\t\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/dr-fassbender.de\/en\/beendigung-einer-betreibung-durch-ruckzug\/\" target=\"_blank\" aria-label=\"Termination of a debt collection by withdrawal\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/dr-fassbender.de\/en\/beendigung-einer-betreibung-durch-ruckzug\/\" target=\"_blank\">\n\t\t\t\tTermination of a debt collection by withdrawal\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-categories premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-align-left fa-fw\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<a href=\"https:\/\/dr-fassbender.de\/en\/category\/aktuelles\/\" rel=\"category tag\">Latest News<\/a>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Every debt collection action is recorded in the debt collection register for the respective debtor. The amount of the debt enforced is recorded in the...<\/p>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"2\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumb-effect-wrapper\">\n\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-container premium-blog-none-effect\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"200\" src=\"https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Beitragsbild-Vertraege-ueber-Hand.png\" class=\"attachment-full size-full wp-image-5829\" alt=\"\" srcset=\"https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Beitragsbild-Vertraege-ueber-Hand.png 370w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Beitragsbild-Vertraege-ueber-Hand-300x162.png 300w, https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Beitragsbild-Vertraege-ueber-Hand-18x10.png 18w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-overlay\">\n\t\t\t\t\t\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/dr-fassbender.de\/en\/koennen-deutsche-insolvenzverwalter-auf-masse-in-der-schweiz-zugreifen\/\" target=\"_blank\" aria-label=\"Can German insolvency administrators access assets in Switzerland?\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/dr-fassbender.de\/en\/koennen-deutsche-insolvenzverwalter-auf-masse-in-der-schweiz-zugreifen\/\" target=\"_blank\">\n\t\t\t\tCan German insolvency administrators access assets in Switzerland?\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-categories premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-align-left fa-fw\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<a href=\"https:\/\/dr-fassbender.de\/en\/category\/aktuelles\/\" rel=\"category tag\">Latest News<\/a>, <a href=\"https:\/\/dr-fassbender.de\/en\/category\/neueste-beitraege\/\" rel=\"category tag\">Neueste Beitr\u00e4ge<\/a>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">This is regulated by the IPRG (Federal Law on Private International Law), there the Art. 166 ff. Since 01.01.2019 there are profound changes and facilitations for the practice...<\/p>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f8f97a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f8f97a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2788b26\" data-id=\"2788b26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82d2a45 elementor-widget elementor-widget-shortcode\" data-id=\"82d2a45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Es ist \u00fcberraschend wie h\u00e4ufig uns Mandanten beauftragen, die Vertr\u00e4ge unterzeichnen, ohne sich jemals \u00fcber deren Inhalt genauere Gedanken gemacht zu machen.<br \/>\nVertr\u00e4ge werden oftmals behandelt, wie das Kleingedruckte, das man ja sowieso nicht \u00e4ndern kann&#8230; <\/p>","protected":false},"author":1,"featured_media":5819,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4,7],"tags":[53,54,49,52,50,51],"class_list":["post-5842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-neueste-beitraege","tag-vertraege-pruefen","tag-vertrags-know-how","tag-vertragsmanagement","tag-vertragspruefung","tag-vertragsstrategie","tag-vertragsverhandlung"],"jetpack_featured_media_url":"https:\/\/dr-fassbender.de\/wp-content\/uploads\/2022\/09\/Beitragsbild-Coaching.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/posts\/5842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/comments?post=5842"}],"version-history":[{"count":18,"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/posts\/5842\/revisions"}],"predecessor-version":[{"id":6223,"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/posts\/5842\/revisions\/6223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/media\/5819"}],"wp:attachment":[{"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/media?parent=5842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/categories?post=5842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dr-fassbender.de\/en\/wp-json\/wp\/v2\/tags?post=5842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}